{"id":2007,"date":"2025-12-23T08:35:12","date_gmt":"2025-12-23T08:35:12","guid":{"rendered":"https:\/\/aandstrading.com\/en\/?page_id=2007"},"modified":"2026-05-12T16:09:41","modified_gmt":"2026-05-12T13:09:41","slug":"home-2","status":"publish","type":"page","link":"https:\/\/aands2.followme.qa\/ar\/home-2\/","title":{"rendered":"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2007\" class=\"elementor elementor-2007\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d59b7b e-con-full e-flex e-con e-parent\" data-id=\"2d59b7b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03b006a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"03b006a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VELOURA COLLECTION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c91783 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7c91783\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0\u062d\u064a\u062b \u064a\u0644\u062a\u0642\u064a \u0627\u0644\u062a\u0631\u0627\u062b \u0628\u0627\u0644\u0641\u062e\u0627\u0645\u0629<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89522fc elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"89522fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aandstrading.com\/ar\/shop-3\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2811003 e-flex e-con-boxed e-con e-parent\" data-id=\"2811003\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18ead0c e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"18ead0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;,&quot;animation_mobile&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc257bf elementor-widget elementor-widget-heading\" data-id=\"cc257bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u0627 \u0627\u0644\u062c\u062f\u064a\u062f \u0644\u062f\u064a\u0646\u0627 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff119a5 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"ff119a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;,&quot;animation_mobile&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c72761e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c72761e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/aandstrading.com\/ar\/shop-3\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"11\" viewBox=\"0 0 21 11\" fill=\"none\"><path d=\"M0.5 5.42524C0.564572 5.24544 0.743024 5.03599 0.949262 5.03599H18.8963L15.2047 1.33848C14.7547 0.930891 15.2521 0.244433 15.7522 0.598193L20.3615 5.19122C20.5474 5.43187 20.545 5.57774 20.3615 5.81566L15.7518 10.4083C15.3487 10.6899 14.8467 10.2745 15.0916 9.82832L18.8959 5.97051H0.949262C0.757113 5.97051 0.585313 5.77432 0.5 5.62026V5.42563V5.42524Z\" fill=\"#623D6A\" stroke=\"#623D6A\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46afcc1 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"46afcc1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:10}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-780b8aa elementor-widget elementor-widget-product_slider_shortcode\" data-id=\"780b8aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"product_slider_shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"sp_product_slider_dynamic_css1829\">#wps-slider-section #sp-woo-product-slider-1829.wps-product-section[data-layout=grid] { margin-left: -20px;}#wps-slider-section #sp-woo-product-slider-1829 .wpsf-grid-item { padding-left: 20px; margin-bottom: 20px;}#wps-slider-section #sp-woo-product-slider-1829 .wpsf-product-title a{ color: #643e6c; font-size: 25px; } #wps-slider-section #sp-woo-product-slider-1829 .wpsf-product-title a:hover{ color: #955b89; }#wps-slider-section #sp-woo-product-slider-1829 .wpsf-product-price { color: #643e6c; font-size: 18px; } #wps-slider-section #sp-woo-product-slider-1829 .wpsf-product-price del span { color: #888888; }#wps-slider-section #sp-woo-product-slider-1829.wps-product-section .star-rating span:before { color: #F4C100; } #wps-slider-section #sp-woo-product-slider-1829.wps-product-section .star-rating:before{ color: #C8C8C8; }#wps-slider-section #sp-woo-product-slider-1829 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button){ color: #643e6c; background-color: #fff6e9; border: 0px none #222222; } #wps-slider-section #sp-woo-product-slider-1829 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button):hover, #wps-slider-section #sp-woo-product-slider-1829 .wpsf-cart-button a.added_to_cart{ color: #ffffff; background-color: #643e6c; border-color: #222222; }#sp-woo-product-slider-1829.sp-wps-custom-template .wps-product-image .wpsf-product-img,#sp-woo-product-slider-1829.sp-wps-theme_one .wps-product-image { border: 0px none #dddddd;}#wps-slider-section #sp-woo-product-slider-1829.sp-wps-theme_one .wpsf-product:hover .wps-product-image, #sp-woo-product-slider-1829.sp-wps-custom-template .sp-wps-product-image-area:hover .wps-product-image .wpsf-product-img { border-color: #dddddd;}#wps-slider-section #sp-woo-product-slider-1829 .wps-pagination ul li .page-numbers {background: transparent; color: #5e5e5e; border: 2px solid #dddddd; } #wps-slider-section #sp-woo-product-slider-1829 .wps-pagination ul li .page-numbers:hover,#wps-slider-section #sp-woo-product-slider-1829 .wps-pagination ul li .page-numbers.current {background: #5e5e5e; color: #ffffff; border-color: #5e5e5e; }<\/style><div id=\"wps-slider-section\" class=\"wps-slider-section wps-slider-section-1829\">\n\t\t<div class=\"wps-preloader\" id=\"wps-preloader-1829\" style=\"\">\n\t\t<img decoding=\"async\" src=\"https:\/\/aands2.followme.qa\/wp-content\/plugins\/woo-product-slider\/src\/Admin\/assets\/images\/spinner.svg\" alt=\"loader-image\"\/>\n\t<\/div>\n\t\t\t<div id=\"sp-woo-product-slider-1829\" class=\"wps-product-section sp-wps-theme_three\" data-swiper='{ \"pauseOnHover\": true, \"infinite\": true, \"slidesToShow\": 3, \"speed\": 600,\"spaceBetween\": 20, \"autoplay\": true, \"autoplaySpeed\": 1000, \"swipe\": true, \"draggable\": true,\"freeMode\":false,\"carousel_accessibility\": false,\"mousewheel\": false,\"adaptiveHeight\": true, \"slidesPerView\":{\"lg_desktop\":3, \"desktop\":3, \"tablet\":2, \"mobile\":1} }'  dir=\"ltr\" data-preloader=\"1\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-007\/\" class=\"wps-product-image\">\n\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-007\/\">AS-V-W-007<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/2007?add-to-cart=5750\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5750\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"5750\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;AS-V-W-007&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;AS-V-W-007&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5750\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\" class=\"wps-product-image\">\n\t<img decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\">\u0627\u0644\u0628\u0648\u062f\u064a\u0647\u0627\u062a<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;17<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5715\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5715\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;\u0627\u0644\u0628\u0648\u062f\u064a\u0647\u0627\u062a&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5715\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\" class=\"wps-product-image\">\n\t<img decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\">AS-V-W-006<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5686\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button\" data-product_id=\"5686\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;AS-V-W-006&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;AS-V-W-006&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5686\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\">AS-V-W-005<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5657\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5657\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-005&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5657\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\">AS-V-W-004<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5628\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5628\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-004&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5628\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\">AS-V-W-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5599\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5599\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5599\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\">AS-V-W-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5570\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5570\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5570\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\">AS-V-W-001<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5541\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5541\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-001&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5541\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\">AS-V-F-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5512\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5512\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5512\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\">AS-V-F-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5483\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5483\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5483\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\">AS-V-F-001<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5454\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5454\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-001&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5454\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\">AS-VS-F-BPI-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5425\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5425\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-BPI-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5425\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\">AS-VS-F-LBU-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5396\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5396\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-LBU-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5396\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\">AS-VS-F-GY-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5367\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5367\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-GY-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5367\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\">AS-VS-F-YE-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5338\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5338\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-YE-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5338\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\">AS-VS-F-OG-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5309\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5309\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-OG-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5309\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n\t\t\t<\/div> <!-- end swiper-wrapper tag  -->\n\t\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ec2f53 e-flex e-con-boxed e-con e-parent\" data-id=\"3ec2f53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-09a98f2 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"09a98f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d143a4 elementor-widget elementor-widget-heading\" data-id=\"6d143a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0641\u0626\u0627\u062a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e81e8b e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"6e81e8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;,&quot;animation_mobile&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-637a552 icon-strt elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"637a552\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"icon-strt\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/aandstrading.com\/ar\/shop-2\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"11\" viewBox=\"0 0 21 11\" fill=\"none\"><path d=\"M0.5 5.42524C0.564572 5.24544 0.743024 5.03599 0.949262 5.03599H18.8963L15.2047 1.33848C14.7547 0.930891 15.2521 0.244433 15.7522 0.598193L20.3615 5.19122C20.5474 5.43187 20.545 5.57774 20.3615 5.81566L15.7518 10.4083C15.3487 10.6899 14.8467 10.2745 15.0916 9.82832L18.8959 5.97051H0.949262C0.757113 5.97051 0.585313 5.77432 0.5 5.62026V5.42563V5.42524Z\" fill=\"#623D6A\" stroke=\"#623D6A\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ac5bb4 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"9ac5bb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-62fe928 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"62fe928\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6ae03 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ad6ae03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/aandstrading.com\/ar\/category-2\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/All-Toubs-1.jpg);\" role=\"img\" aria-label=\"All Toubs (1)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t\u062a\u0648\u0628\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\t\u0639\u0631\u0636 \u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0629\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1c7d41 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"f1c7d41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0589e3e elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"0589e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/aandstrading.com\/ar\/shop-3\/?wpf_filter_cat_list_2=78&amp;wpf_fbv=1\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/BodySuits.jpg);\" role=\"img\" aria-label=\"BodySuits\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t\u0628\u0648\u062f\u064a\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\t\u0639\u0631\u0636 \u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0629\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1db5bb e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"e1db5bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-aa2f01a e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"aa2f01a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6516ceb elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"6516ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/aandstrading.com\/ar\/category-2\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/All-Toubs-1.jpg);\" role=\"img\" aria-label=\"All Toubs (1)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t\u062a\u0648\u0628\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-744da77 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"744da77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-651dcea elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"651dcea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/aandstrading.com\/ar\/shop-3\/?wpf_filter_cat_list_2=78&amp;wpf_fbv=1\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/BodySuits.jpg);\" role=\"img\" aria-label=\"BodySuits\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t\u0628\u0648\u062f\u064a\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cad9c2 e-flex e-con-boxed e-con e-parent\" data-id=\"4cad9c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b4a286d e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"b4a286d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2c9d43 elementor-widget elementor-widget-heading\" data-id=\"e2c9d43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0623\u0643\u062b\u0631 \u0645\u0628\u064a\u0639\u0627\u064b <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a76703e e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"a76703e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;,&quot;animation_mobile&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c197f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b8c197f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/aandstrading.com\/ar\/shop-3\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"11\" viewBox=\"0 0 21 11\" fill=\"none\"><path d=\"M0.5 5.42524C0.564572 5.24544 0.743024 5.03599 0.949262 5.03599H18.8963L15.2047 1.33848C14.7547 0.930891 15.2521 0.244433 15.7522 0.598193L20.3615 5.19122C20.5474 5.43187 20.545 5.57774 20.3615 5.81566L15.7518 10.4083C15.3487 10.6899 14.8467 10.2745 15.0916 9.82832L18.8959 5.97051H0.949262C0.757113 5.97051 0.585313 5.77432 0.5 5.62026V5.42563V5.42524Z\" fill=\"#623D6A\" stroke=\"#623D6A\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1c9078 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"d1c9078\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bdd236 elementor-widget elementor-widget-product_slider_shortcode\" data-id=\"9bdd236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"product_slider_shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"sp_product_slider_dynamic_css1401\">#wps-slider-section #sp-woo-product-slider-1401.wps-product-section[data-layout=grid] { margin-left: -20px;}#wps-slider-section #sp-woo-product-slider-1401 .wpsf-grid-item { padding-left: 20px; margin-bottom: 20px;}#wps-slider-section #sp-woo-product-slider-1401 .wpsf-product-title a{ color: #643e6c; font-size: 25px; } #wps-slider-section #sp-woo-product-slider-1401 .wpsf-product-title a:hover{ color: #955b89; }#wps-slider-section #sp-woo-product-slider-1401 .wpsf-product-price { color: #643e6c; font-size: 18px; } #wps-slider-section #sp-woo-product-slider-1401 .wpsf-product-price del span { color: #888888; }#wps-slider-section #sp-woo-product-slider-1401.wps-product-section .star-rating span:before { color: #F4C100; } #wps-slider-section #sp-woo-product-slider-1401.wps-product-section .star-rating:before{ color: #C8C8C8; }#wps-slider-section #sp-woo-product-slider-1401 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button){ color: #643e6c; background-color: #fff6e9; border: 1px none #222222; } #wps-slider-section #sp-woo-product-slider-1401 .wpsf-cart-button a:not(.sp-wqvpro-view-button):not(.sp-wqv-view-button):hover, #wps-slider-section #sp-woo-product-slider-1401 .wpsf-cart-button a.added_to_cart{ color: #fff6e9; background-color: #643e6c; border-color: #222222; }#sp-woo-product-slider-1401.sp-wps-custom-template .wps-product-image .wpsf-product-img,#sp-woo-product-slider-1401.sp-wps-theme_one .wps-product-image { border: 0px none #dddddd;}#wps-slider-section #sp-woo-product-slider-1401.sp-wps-theme_one .wpsf-product:hover .wps-product-image, #sp-woo-product-slider-1401.sp-wps-custom-template .sp-wps-product-image-area:hover .wps-product-image .wpsf-product-img { border-color: #dddddd;}#wps-slider-section #sp-woo-product-slider-1401 .wps-pagination ul li .page-numbers {background: transparent; color: #5e5e5e; border: 2px solid #dddddd; } #wps-slider-section #sp-woo-product-slider-1401 .wps-pagination ul li .page-numbers:hover,#wps-slider-section #sp-woo-product-slider-1401 .wps-pagination ul li .page-numbers.current {background: #5e5e5e; color: #ffffff; border-color: #5e5e5e; }<\/style><div id=\"wps-slider-section\" class=\"wps-slider-section wps-slider-section-1401\">\n\t\t<div class=\"wps-preloader\" id=\"wps-preloader-1401\" style=\"\">\n\t\t<img decoding=\"async\" src=\"https:\/\/aands2.followme.qa\/wp-content\/plugins\/woo-product-slider\/src\/Admin\/assets\/images\/spinner.svg\" alt=\"loader-image\"\/>\n\t<\/div>\n\t\t\t<div id=\"sp-woo-product-slider-1401\" class=\"wps-product-section sp-wps-theme_three\" data-swiper='{ \"pauseOnHover\": true, \"infinite\": true, \"slidesToShow\": 3, \"speed\": 600,\"spaceBetween\": 20, \"autoplay\": true, \"autoplaySpeed\": 1000, \"swipe\": true, \"draggable\": true,\"freeMode\":false,\"carousel_accessibility\": false,\"mousewheel\": false,\"adaptiveHeight\": false, \"slidesPerView\":{\"lg_desktop\":3, \"desktop\":3, \"tablet\":2, \"mobile\":1} }'  dir=\"ltr\" data-preloader=\"1\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-007\/\" class=\"wps-product-image\">\n\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D13-2-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-007\/\">AS-V-W-007<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/2007?add-to-cart=5750\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5750\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"5750\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;AS-V-W-007&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;AS-V-W-007&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5750\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\" class=\"wps-product-image\">\n\t<img decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/Body-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\">\u0627\u0644\u0628\u0648\u062f\u064a\u0647\u0627\u062a<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;17<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/bodeysuits\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5715\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5715\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;\u0627\u0644\u0628\u0648\u062f\u064a\u0647\u0627\u062a&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5715\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\" class=\"wps-product-image\">\n\t<img decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D16-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\">AS-V-W-006<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-006\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5686\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button\" data-product_id=\"5686\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;AS-V-W-006&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;AS-V-W-006&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5686\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D15-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\">AS-V-W-005<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-005\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5657\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5657\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-005&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5657\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D24-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\">AS-V-W-004<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-004\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5628\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5628\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-004&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5628\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D26-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\">AS-V-W-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5599\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5599\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5599\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D28-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\">AS-V-W-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5570\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5570\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5570\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D29-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\">AS-V-W-001<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-w-001\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5541\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5541\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-W-001&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5541\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D27-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\">AS-V-F-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5512\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5512\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5512\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D3-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\">AS-V-F-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5483\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5483\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5483\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D18-2-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\">AS-V-F-001<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;80<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-v-f-001\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5454\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5454\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-V-F-001&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5454\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D11-1--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\">AS-VS-F-BPI-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-bpi-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5425\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5425\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-BPI-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5425\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D2-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\">AS-VS-F-LBU-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-lbu-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5396\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5396\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-LBU-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5396\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D25-1-1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\">AS-VS-F-GY-003<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-gy-003\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5367\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5367\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-GY-003&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5367\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D17-2-New--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\">AS-VS-F-YE-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-ye-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5338\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5338\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-YE-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5338\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n<div class=\"wpsf-product  swiper-slide\">\n\t<div class=\"sp-wps-product-image-area\">\n\t\t<a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\" class=\"wps-product-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1638\" height=\"2048\" src=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1638x2048.jpg\" class=\"wpsf-product-img wp-post-image\" alt=\"\" srcset=\"https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1638x2048.jpg 1638w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--600x750.jpg 600w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1080x1350.jpg 1080w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--240x300.jpg 240w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--819x1024.jpg 819w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--120x150.jpg 120w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--768x960.jpg 768w, https:\/\/aands2.followme.qa\/wp-content\/uploads\/2026\/05\/D23-1New--1229x1536.jpg 1229w\" sizes=\"(max-width: 1638px) 100vw, 1638px\" \/><\/a>\n\t\t<div class=\"sp-wps-product-details\">\n\t\t\t<div class=\"sp-wps-product-details-inner\">\n\t\t\t\t\t\t<div class=\"wpsf-product-title\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\">AS-VS-F-OG-002<\/a><\/div>\n\t\t<div class=\"wpsf-product-price\"> <span class=\"woocommerce-Price-amount amount\"><span class=\"woocommerce-Price-currencySymbol\">&#036;<\/span>&nbsp;220<\/span><\/div>\n\t\t<div class=\"wpsf-cart-button\"><p class=\"product woocommerce add_to_cart_inline \" style=\"border:4px solid #ccc; padding: 12px;\"><a href=\"https:\/\/aands2.followme.qa\/ar\/product\/as-vs-f-og-002\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_5309\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"5309\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;AS-VS-F-OG-002&quot;\" rel=\"nofollow\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_5309\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/p><\/div>\n\t\t\t\t<\/div> <!-- sp-wps-product-details-inner. -->\n\t\t<\/div> <!--  sp-wps-product-details. -->\n\t<\/div> <!-- sp-wps-product-image-area.  -->\n<\/div> <!-- wpsf-product. -->\n\t\t\t<\/div> <!-- end swiper-wrapper tag  -->\n\t\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea8f435 e-con-full e-flex e-con e-parent\" data-id=\"ea8f435\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1887192 e-con-full e-flex e-con e-child\" data-id=\"1887192\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07016ad elementor-widget elementor-widget-spacer\" data-id=\"07016ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa01e30 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"aa01e30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062a\u0645\u064a\u0632\u064a \u0628\u0623\u0646\u0627\u0642\u062a\u0643<br> \u0643\u0644 \u064a\u0648\u0645<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f03c2bf animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f03c2bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u062a\u0642\u062f\u0651\u0645 \u0644\u0643 <strong>\u0623\u064a \u0627\u0646\u062f \u0627\u0633<\/strong> \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0627\u0644\u0623\u0632\u064a\u0627\u0621 \u0627\u0644\u0633\u0648\u062f\u0627\u0646\u064a\u0629 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0643\u0644 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0627\u062a.\u0645\u0646 \u0627\u0644\u0625\u0637\u0644\u0627\u0644\u0627\u062a \u0627\u0644\u064a\u0648\u0645\u064a\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0647\u0631\u0627\u062a \u0627\u0644\u0641\u0627\u062e\u0631\u0629\u060c \u0646\u0645\u0632\u062c \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0628\u0627\u0644\u062a\u0642\u0627\u0644\u064a\u062f \u0628\u0623\u0633\u0644\u0648\u0628 \u064a\u0639\u0643\u0633 \u0627\u0644\u062a\u0645\u064a\u0651\u0632 \u0648\u0627\u0644\u062c\u0645\u0627\u0644.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4c422 elementor-mobile-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1f4c422\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_mobile&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aandstrading.com\/ar\/product-category\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0639\u0631\u0636 \u0627\u0644\u0641\u0626\u0627\u062a<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-830002e e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"830002e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71e6d83 elementor-hidden-desktop elementor-widget elementor-widget-spacer\" data-id=\"71e6d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f242bbd e-flex e-con-boxed e-con e-parent\" data-id=\"f242bbd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-46435ed e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"46435ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35489c4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"35489c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"48\" viewBox=\"0 0 41 48\" fill=\"none\"><path d=\"M19.539 25.6843L19.5296 28.1247L19.5331 28.1472C19.6198 28.7442 20.0896 29.0505 20.5184 29.0505C20.5278 29.0505 20.5372 29.0505 20.5454 29.0505C20.9836 29.0375 21.4522 28.71 21.512 28.01C21.5471 27.5938 21.5319 27.1552 21.5167 26.7319C21.5038 26.3725 21.4897 26.0036 21.5096 25.656C21.5483 25.6264 21.5893 25.598 21.6303 25.5685C21.8002 25.4467 21.9759 25.3202 22.1294 25.1192C22.7211 24.3388 22.659 23.1659 21.9877 22.4482C21.5319 21.9611 20.8594 21.7388 20.188 21.8559C19.5085 21.9729 18.9414 22.4139 18.6696 23.0335C18.2396 24.0148 18.597 25.0825 19.539 25.6867V25.6843Z\" fill=\"#623D6A\"><\/path><path d=\"M16.1506 14.9025C15.3445 16.0446 15.2578 17.305 15.286 18.4318H14.2034C13.8624 18.4318 13.1407 18.7297 12.8794 18.8905C12.0452 19.4049 11.5016 20.3389 11.4243 21.3888V21.422C11.4512 22.0592 11.4372 22.7119 11.4243 23.3433C11.388 25.0931 11.3505 26.9021 12.1507 28.6035C13.2145 30.8654 15.6421 32.5467 18.0557 32.6945C18.7926 32.7394 19.6819 32.7619 20.5618 32.7619C21.4417 32.7619 22.3192 32.7394 23.0222 32.6945C25.6103 32.5278 28.1012 30.6608 29.0795 28.1554C29.7368 26.473 29.663 24.5611 29.5927 22.7131C29.5693 22.1101 29.5482 21.539 29.5505 20.9821V20.9537L29.5458 20.9254C29.3935 20.1084 28.8604 19.3138 28.1867 18.8988C27.4041 18.4176 26.5582 18.4129 25.7345 18.4259C25.7345 18.3561 25.7345 18.2875 25.7357 18.2178C25.7392 17.772 25.7439 17.3121 25.6759 16.8534C25.3725 14.7831 23.6455 13.1881 21.5694 13.058C19.6608 12.9398 17.5109 12.9741 16.1506 14.9013V14.9025ZM13.7324 21.474C13.7781 21.1134 13.9972 20.8568 14.3381 20.7646L26.5957 20.7516C26.9565 20.7882 27.2471 21.0696 27.2987 21.4302C27.2764 22.0782 27.2928 22.7462 27.3092 23.3929C27.3279 24.1295 27.3467 24.8922 27.3069 25.6146C27.1698 28.0869 25.3936 30.0366 22.9835 30.3652C22.2525 30.3262 21.5167 30.3522 20.8055 30.3771C18.6017 30.4539 16.5209 30.5272 14.9286 28.6769C13.6164 27.1516 13.6679 25.2977 13.723 23.3362C13.7406 22.7249 13.7582 22.0947 13.7312 21.474H13.7324ZM23.4335 18.4318H17.5976V17.4185C17.5976 16.5696 18.3544 15.6462 19.2191 15.4416C19.6971 15.3281 21.3234 15.3281 21.8166 15.4416C22.6485 15.632 23.4346 16.572 23.4346 17.3748V18.433L23.4335 18.4318Z\" fill=\"#623D6A\"><\/path><path d=\"M40.9973 12.7506C41.0032 11.8414 41.0114 10.8115 40.8485 10.0832C40.7314 9.55707 40.3564 9.2272 39.7952 9.15625C39.548 9.12551 39.2926 9.10778 39.0454 9.09122C38.7724 9.07349 38.4912 9.05457 38.2229 9.01674C31.9887 8.13589 25.765 3.8676 22.6098 1.40122C22.4387 1.26761 22.2501 1.09736 22.0498 0.917639C21.7533 0.650428 21.4464 0.373758 21.171 0.196405C20.7305 -0.0885411 20.2349 -0.0625294 19.7768 0.268529C19.4101 0.533375 19.0434 0.850245 18.6884 1.15647C18.3908 1.41304 18.0838 1.67907 17.7839 1.90727C10.815 7.20656 5.46069 8.63247 2.88896 9.01201C2.61012 9.05339 2.31018 9.07231 2.01962 9.09122C1.73257 9.11014 1.43615 9.12906 1.15496 9.16926C0.653499 9.2402 0.278578 9.60791 0.175475 10.1281C0.0794011 10.6082 0.0536253 11.4157 0.0360509 11.9513L0.0313644 12.0802C-0.209991 19.3044 0.945234 26.1466 3.37167 31.8668C6.19413 38.5211 10.5889 43.4645 16.4353 46.5623L16.624 46.6628C17.9479 47.3663 19.143 48 20.5208 48C21.0738 48 21.6573 47.8971 22.2899 47.6559C24.5746 46.7834 26.8042 45.2924 28.2711 44.194C32.6963 40.8834 36.046 36.2581 38.2276 30.4456C40.1116 25.4242 41.0688 19.5527 40.9962 13.4647C40.9938 13.2484 40.9962 13.006 40.9962 12.7494L40.9973 12.7506ZM38.7419 14.4425C38.7419 14.4638 38.7337 14.4981 38.7255 14.5348C38.7126 14.5927 38.6962 14.6648 38.6939 14.7476C38.3178 34.3651 28.5874 42.0386 22.8219 44.8668L22.625 44.9637C21.8658 45.3397 21.0058 45.7665 20.2208 45.6826C19.6854 45.6258 18.4107 44.9732 17.8659 44.6953L17.8003 44.6622C10.9439 41.1589 6.11328 34.7305 3.83095 26.0745C2.61597 21.4681 2.12975 16.5329 2.38516 11.4027C2.57145 11.372 2.87608 11.3412 3.02839 11.3259C3.17133 11.3117 3.27443 11.301 3.33418 11.2904C8.75765 10.4036 14.3744 7.58846 20.4997 2.68407C24.7539 6.04194 31.1849 10.4947 38.6588 11.4027L38.7419 14.4425Z\" fill=\"#623D6A\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u062f\u0641\u0639 \u0622\u0645\u0646<br> \u0648\u0645\u0636\u0645\u0648\u0646\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-597519d e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"597519d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccdba02 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ccdba02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"55\" height=\"48\" viewBox=\"0 0 55 48\" fill=\"none\"><path d=\"M33.1395 21.2586C32.2062 21.2586 31.4469 22.0234 31.4469 22.9636C31.4469 23.9038 32.2062 24.6675 33.1395 24.6675C34.0729 24.6675 34.831 23.9027 34.831 22.9636C34.831 22.0246 34.0717 21.2586 33.1395 21.2586Z\" fill=\"#623D6A\"><\/path><path d=\"M21.8845 21.2756C20.8411 21.443 20.4076 22.3708 20.5176 23.199C20.6547 24.2342 21.4274 24.6743 22.1541 24.6743C22.2192 24.6743 22.2832 24.6709 22.3461 24.6641C22.9728 24.5962 23.4636 24.2421 23.6939 23.6934C23.9432 23.0971 23.8466 22.3572 23.4524 21.8515C23.0829 21.3774 22.5258 21.1726 21.8845 21.2756Z\" fill=\"#623D6A\"><\/path><path d=\"M27.6541 21.2609C26.7219 21.2609 25.9638 22.0246 25.9638 22.9636C25.9638 23.9027 26.7219 24.6664 27.6541 24.6664C28.5863 24.6664 29.3444 23.9027 29.3444 22.9636C29.3444 22.0246 28.5863 21.2609 27.6541 21.2609Z\" fill=\"#623D6A\"><\/path><path d=\"M40.9993 31.2227C41.17 30.8233 41.3677 30.4296 41.5586 30.0483C41.8405 29.4849 42.1326 28.9011 42.3527 28.2811C44.3025 22.7837 43.0344 16.4819 39.1203 12.2268C37.0919 10.0217 34.5289 8.4559 31.7064 7.70013C29.0524 6.98963 26.221 6.99528 23.5187 7.71824C20.8377 8.43553 18.3994 9.82827 16.4664 11.7448C14.4111 13.7847 12.9712 16.3926 12.3041 19.2889C11.5942 22.3663 11.7627 25.4968 12.7893 28.3411C13.7518 31.0066 15.4376 33.378 17.6648 35.1973C19.9167 37.038 22.6078 38.2248 25.4471 38.6288C28.4268 39.0542 31.493 38.5903 34.3222 37.2869L42.5874 40.5555L42.6189 40.5657C42.7761 40.6075 42.9289 40.6279 43.0715 40.6279C43.3983 40.6279 43.6802 40.5216 43.8757 40.3156C44.1531 40.0249 44.2216 39.5893 44.07 39.0892L40.9993 31.2227ZM38.6676 31.1084L41.1217 37.6535L34.4356 35.0049L34.3626 35.0151C33.7404 35.1022 33.162 35.3523 32.6027 35.5955C32.2399 35.7528 31.8648 35.9157 31.4863 36.0288C26.8398 37.417 21.9474 36.2732 18.3971 32.9684C14.8469 29.6637 13.3295 24.8417 14.337 20.0684C15.3747 15.1559 18.8812 11.3579 23.7175 9.91086C28.5661 8.46042 33.5809 9.72305 37.1334 13.2892C41.3531 17.5262 42.2999 24.0249 39.4875 29.4612C39.4359 29.5596 39.3359 29.7135 39.2292 29.8752C38.881 30.4047 38.6542 30.7724 38.6654 31.0621L38.6676 31.1084Z\" fill=\"#623D6A\"><\/path><path d=\"M54.9757 20.8513C54.9038 18.2887 52.9844 16.0724 50.6078 15.8065C50.4685 15.7907 50.2462 15.7963 49.9867 15.802C49.7216 15.8076 49.2555 15.8189 49.0624 15.7827C46.0007 6.14448 36.5427 -0.478634 26.5253 0.0270942C17.1235 0.497749 8.89308 6.80408 5.97515 15.7443C3.6536 15.673 1.95429 16.4559 0.917624 18.0693C-0.140379 19.7154 -0.0595125 23.1582 0.0820037 25.0646C0.272938 27.6238 2.1879 29.7123 4.53415 29.9239C4.65994 29.9352 4.85649 29.9295 5.08449 29.9228C5.33608 29.9148 5.83924 29.9001 6.01221 29.942C6.09195 30.1208 6.27952 30.6695 6.40868 31.0451C6.55132 31.4614 6.68497 31.854 6.7591 32.0215C9.64221 38.5914 15.5365 43.4937 22.5483 45.1659C22.8762 46.3233 23.549 47.2058 24.4116 47.6017C24.9866 47.8654 26.2749 48 27.5553 48C28.7772 48 29.9914 47.8778 30.5675 47.6312C31.9479 47.0395 32.7004 45.6309 32.4836 44.0436C32.2725 42.4902 31.2066 41.3633 29.769 41.1732C28.8671 41.0544 26.185 41.0544 25.2843 41.1732C24.6407 41.2581 23.8972 41.7174 23.4962 42.127C23.4097 42.2152 23.3199 42.3442 23.2233 42.4811C23.1548 42.5784 23.038 42.7459 22.9638 42.8228C19.6315 42.0693 16.4968 40.4163 13.8944 38.037C11.3213 35.686 9.38277 32.7331 8.27984 29.4894C8.81783 28.9498 9.22665 28.4271 9.31089 27.4869L9.31313 27.4665V27.4462C9.23451 26.0613 9.28168 24.5894 9.32773 23.1661C9.3794 21.5901 9.43219 19.9598 9.3165 18.4256C9.26484 17.7457 9.11434 17.2456 8.84141 16.8542C8.76054 16.7376 8.65385 16.6415 8.55052 16.5487C8.43708 16.4469 8.29556 16.319 8.29893 16.2432C8.30792 16.0294 8.73696 14.984 9.12894 14.1377C11.1686 9.73776 14.7413 6.20558 19.1912 4.19058C23.6445 2.17333 28.6571 1.82373 33.3046 3.20515C39.51 5.0493 44.6574 10.033 46.779 16.2353C46.1624 16.8394 45.8131 17.3814 45.739 18.3329C45.6165 19.8942 45.6727 21.5596 45.7266 23.1684C45.7749 24.6234 45.8255 26.127 45.7435 27.5389V27.5819C45.8356 28.5923 46.5847 29.7542 47.791 29.9194C49.4532 30.1468 51.0425 29.942 52.2633 29.3424C53.7212 28.6262 54.6208 27.376 54.8656 25.7265C55.0307 24.6087 55.0105 22.0506 54.9768 20.8536L54.9757 20.8513ZM52.5823 24.1301C52.6048 24.6109 52.6272 25.1065 52.5306 25.5997C52.3599 26.4732 51.339 27.4348 50.4292 27.5774C50.0361 27.6396 48.5749 27.6634 48.2436 27.6C48.1908 27.5898 48.1346 27.565 48.074 27.3952L48.0526 18.4528C48.0549 18.3216 48.147 18.153 48.1942 18.1337C48.4064 18.0772 49.9362 18.0874 50.281 18.1247C50.8774 18.1903 51.6961 18.6712 52.069 19.1746C52.6834 20.0062 52.6317 21.3921 52.5857 22.6152C52.5744 22.9161 52.5643 23.2001 52.5632 23.4694C52.5632 23.6911 52.5733 23.9151 52.5834 24.1312L52.5823 24.1301ZM6.88377 27.5729C6.87703 27.5808 6.86805 27.5865 6.85906 27.5887C6.64229 27.6487 5.12829 27.6374 4.77226 27.5978C3.76143 27.4869 2.77081 26.6033 2.51811 25.585C2.39119 25.0737 2.42376 24.6053 2.45746 24.1108C2.4743 23.8744 2.49115 23.6289 2.49003 23.3754C2.49003 23.1333 2.48216 22.8844 2.47543 22.6208C2.42376 20.6884 2.36536 18.4992 4.62176 18.1451C4.77563 18.1213 5.21927 18.1066 5.67864 18.1066C6.138 18.1066 6.65016 18.1224 6.85457 18.1575C6.9096 18.2989 6.96913 18.5558 7.0017 19.0208C7.15445 21.1817 7.11065 24.2511 7.0017 26.334C6.99384 26.48 6.97137 26.6316 6.94667 26.7922C6.9096 27.0423 6.87029 27.3013 6.88265 27.5717L6.88377 27.5729ZM24.8474 44.4825C24.8485 44.1013 25.0394 43.6182 25.574 43.5084C25.802 43.462 26.6646 43.4383 27.5261 43.4383C28.3875 43.4383 29.2501 43.462 29.4781 43.5084C30.0003 43.6159 30.2216 44.0979 30.2104 44.5278C30.198 44.9769 29.9296 45.4951 29.2141 45.6003C28.5447 45.6988 26.2535 45.7067 25.6875 45.5868C25.1046 45.4634 24.8451 44.943 24.8462 44.4825H24.8474Z\" fill=\"#623D6A\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u062f\u0639\u0645 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0639\u0644\u0649<br> \u0645\u062f\u0627\u0631 \u0627\u0644\u064a\u0648\u0645\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15ae481 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"15ae481\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb8562f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fb8562f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"40\" viewBox=\"0 0 50 40\" fill=\"none\"><path d=\"M18.5859 20.9039L18.693 23.6494C18.8366 25.2057 18.9865 26.7607 19.2712 28.2977L19.3153 28.3503C19.348 28.3567 19.5345 28.2617 19.5483 28.3593C16.5539 29.4485 13.5053 30.471 10.3484 30.9714C9.6858 31.0766 8.99546 31.1715 8.32527 31.1882C8.24213 31.1626 7.53541 29.9745 7.43715 29.8013C4.04718 23.7816 4.11647 16.2223 7.43715 10.1872C11.9055 2.07106 21.2855 -1.81893 30.1113 0.820155C36.1555 2.62787 41.1517 7.42235 43.103 13.5409L41.706 14.9393C41.1718 13.2124 40.4802 11.5163 39.451 10.0345C36.8245 10.6619 34.1651 11.1712 31.4756 11.4496C31.9001 13.9373 32.1483 16.4648 32.1546 18.9948L32.2088 19.0859H36.6191L33.9586 20.9039H32.1911L32.1382 22.0675L30.299 23.1581L30.3695 20.9039H18.5859ZM19.6567 9.84846C20.3521 9.88824 21.0487 9.92544 21.7453 9.95752C24.2447 10.0756 26.7465 10.0435 29.2446 9.84846L29.3277 9.79458C28.7923 7.70333 28.1474 5.41321 26.9342 3.61833C24.5155 0.0388218 22.413 2.47391 21.1142 5.31442C20.4604 6.74623 19.9955 8.30761 19.6567 9.84846ZM36.963 6.91558C34.572 4.56773 31.4542 2.88575 28.1914 2.21218L28.9473 3.4246C29.9891 5.36831 30.6706 7.5019 31.1191 9.66756C33.5315 9.38916 35.9338 8.99785 38.2959 8.43077C38.321 8.39742 37.8335 7.83804 37.7781 7.77646C37.5324 7.50062 37.2238 7.17474 36.9618 6.91686L36.963 6.91558ZM20.764 2.24939C16.855 3.05767 13.271 5.32725 10.7654 8.4667C13.1022 8.97091 15.4554 9.4161 17.8363 9.65217C18.4511 7.05799 19.2384 4.44456 20.7627 2.24811L20.764 2.24939ZM6.76697 19.0859H16.8008C16.8298 17.3847 16.9306 15.6706 17.1271 13.9809C17.2254 13.1342 17.3841 12.2951 17.4798 11.4483C14.8507 11.1674 12.2469 10.685 9.67824 10.0666C9.62155 10.0666 9.60391 10.1076 9.57242 10.141C9.45904 10.2603 9.24237 10.667 9.14663 10.8351C8.14513 12.5825 7.38676 14.6853 7.02899 16.679C6.97735 16.9664 6.67879 18.9948 6.76823 19.0859H6.76697ZM18.5859 19.0859H30.3695C30.3431 17.0075 30.2096 14.9072 29.8997 12.8558C29.8782 12.7185 29.7296 11.6382 29.6691 11.6292C26.6168 11.9076 23.5216 11.9282 20.4616 11.7409C20.0636 11.7165 19.6617 11.6716 19.2649 11.6318C19.1994 12.2617 19.0659 12.8814 18.984 13.5088C18.829 14.6891 18.7434 15.8797 18.6564 17.0665L18.5859 19.0859ZM16.8008 20.9039H6.7846C6.74807 20.9308 6.74555 20.936 6.74555 20.9783C6.74555 21.2233 6.77957 21.5441 6.80224 21.7943C7.07057 24.6745 8.06073 27.4573 9.56864 29.886L9.64044 29.9232C11.6712 29.4434 13.7208 29.0238 15.7867 28.7275C16.3461 28.6466 16.9167 28.5786 17.4786 28.5414C17.4483 28.0706 17.3337 27.6049 17.2682 27.1366C17.0276 25.3866 16.8613 23.5276 16.7983 21.7609C16.7882 21.4761 16.8084 21.1887 16.7996 20.9052L16.8008 20.9039ZM46.7601 2.15958C47.3484 1.495 46.8357 0.49043 45.9576 0.616161L41.5699 2.36614C41.1467 2.60862 40.9841 3.11668 41.1051 3.58882C41.1832 3.89673 41.6795 4.33038 41.9151 4.56516C42.7957 5.44272 43.7354 6.26639 44.616 7.14267C45.5003 7.8406 46.5358 6.76804 45.9022 5.86995L44.7596 4.76146C46.2751 4.96032 48.079 5.52611 48.1874 7.36205C48.3184 9.6047 45.8153 12.6761 44.3678 14.2362C40.8191 18.0582 35.9943 21.4119 31.5235 24.0292C26.0851 27.2123 19.8746 30.0861 13.7661 31.6193C10.5147 32.4353 -0.771343 34.6664 2.30873 27.6972C2.44101 27.397 2.60099 27.0981 2.76224 26.8133C2.9701 26.4451 3.49793 25.7856 3.51935 25.402C3.56848 24.5103 2.47124 24.0857 1.91191 24.7823C0.669804 26.3296 -0.470264 29.2548 0.1974 31.219C1.61083 35.3733 8.484 34.5817 11.7757 33.9543C17.2002 32.9202 22.8463 30.6288 27.7719 28.1347C33.568 25.2006 39.7307 21.2772 44.4233 16.7278C46.973 14.2555 52.0875 8.54496 49.0805 4.85383C48.0009 3.52852 46.6454 3.34249 45.1237 2.95503C45.0871 2.94605 45.0355 2.96016 45.0468 2.90756C45.62 2.67534 46.2587 2.53293 46.7626 2.16343L46.7601 2.15958ZM41.7249 20.9039L44.1524 18.8306L44.1902 20.1598C44.0252 34.4457 29.7334 44.0295 16.7051 38.3293C14.9944 37.5813 13.3655 36.5446 11.9458 35.322L14.207 34.8049C16.1722 36.2059 18.402 37.249 20.764 37.7404L19.9363 36.383C19.4602 35.4464 19.0268 34.4842 18.7257 33.4719L20.3861 32.8689C20.9718 34.3123 21.5161 35.8454 22.5478 37.0322C25.8118 40.7926 28.2607 34.0903 28.9586 31.6308C29.0871 31.178 29.237 30.6455 29.3277 30.1875C29.3416 30.1169 29.3303 30.1464 29.2799 30.14C28.655 30.0566 27.9836 30.0554 27.3525 30.0297L27.0841 29.9578L31.6179 27.5933C31.5928 27.814 31.5676 28.0359 31.5373 28.2566C31.526 28.3464 31.4252 28.4991 31.5335 28.5337C34.2118 28.8057 36.8522 29.3433 39.4725 29.9412C41.2122 27.2597 42.2074 24.1241 42.3648 20.9026H41.7224L41.7249 20.9039ZM38.2959 31.5231C35.9225 31.0291 33.5378 30.5544 31.1203 30.3248C30.5421 32.9382 29.7208 35.6004 28.1549 37.7776C31.7175 37.0604 35.115 35.1193 37.5828 32.4147C37.7668 32.2133 37.986 31.9708 38.1522 31.7579C38.1774 31.7245 38.3223 31.5462 38.2959 31.5231Z\" fill=\"#623D6A\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0634\u062d\u0646 \u0644\u062c\u0645\u064a\u0639 <br>\u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0639\u0627\u0644\u0645\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d216b13 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"d216b13\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1922c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4a1922c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"39\" height=\"48\" viewBox=\"0 0 39 48\" fill=\"none\"><path d=\"M27.1855 47.9974H26.5659L26.0011 47.3632L22.2874 39.1474C20.5979 40.7041 18.3884 40.6976 16.7063 39.1474L12.9503 47.4481L12.4278 47.9987H11.8082L8.33342 44.0877C6.62774 43.9101 4.77276 44.1558 3.13053 43.6965C2.49479 43.1742 2.85558 42.6326 3.10565 42.0086C4.27014 39.1152 5.8315 36.371 6.95245 33.4532C5.7158 32.056 3.43658 31.9724 2.56321 30.1699C1.58907 28.1604 2.82323 26.2087 1.91005 24.3021C1.1163 22.6437 -0.243514 21.7933 0.0376559 19.5895C0.242935 17.9736 1.91752 16.7167 2.20491 15.2873C2.54579 13.5878 1.69233 11.9745 2.53086 10.2351C3.46146 8.30272 5.885 8.26927 7.0383 6.8142C7.93779 5.67948 8.03732 4.15494 9.26526 3.08712C11.0817 1.50725 12.8981 2.69858 14.8202 2.29075C15.8093 2.08105 17.1144 0.705742 18.2129 0.283759C20.4524 -0.576932 21.3183 0.701882 23.009 1.70281C25.2198 3.01121 26.9155 1.66292 28.9882 2.57379C30.7735 3.35729 30.9228 5.5058 31.9592 6.8142C33.1287 8.28986 35.5186 8.26798 36.4666 10.2351C37.3052 11.9745 36.4517 13.5878 36.7926 15.2873C37.075 16.6961 38.7421 17.989 38.9586 19.5895C39.2398 21.6634 38.0267 22.5048 37.2131 24.0486C36.0996 26.1598 37.4432 28.0819 36.4343 30.1712C35.5621 31.9762 33.2991 32.0791 32.0425 33.4532C33.166 36.371 34.7261 39.1178 35.8918 42.0112C36.2153 42.8153 36.5375 43.4212 35.5572 43.8908L30.6641 44.0889L27.1892 48L27.1855 47.9974ZM19.2182 1.83403C18.1445 1.99613 16.8046 3.55155 15.5281 3.92336C14.1173 4.33505 13.0673 3.96453 11.7523 3.98383C9.53648 4.01599 9.39963 7.07022 7.9042 8.48155C6.65511 9.66001 4.05242 10.0009 3.87078 11.878C3.74139 13.2211 4.21789 14.4228 3.8347 15.9473C3.4739 17.3766 1.72717 18.9205 1.75329 20.2186C1.78191 21.6273 3.82226 23.2445 4.00017 25.3467C4.1507 27.1234 3.18527 28.9619 4.87354 30.0889C6.3503 31.0731 7.57575 31.149 8.68426 32.8189C9.54519 34.1144 9.73803 36.16 11.4997 36.3208C12.7724 36.4366 13.9257 35.9761 15.3353 36.3311C17.0646 36.766 18.4493 39.1152 20.2919 38.3639C21.8694 37.7206 22.4753 36.3594 24.5169 36.1909C25.6864 36.0944 27.3983 36.6065 28.3724 36.0738C29.242 35.5978 29.9425 32.999 30.9042 32.0213C31.8559 31.0538 34.5357 30.2536 34.9388 29.2668C35.3581 28.2427 34.8953 26.5509 34.9973 25.3493C35.174 23.2484 37.294 21.5347 37.2454 20.0925C37.2056 18.8832 35.5136 17.3419 35.1628 15.9499C34.7784 14.4266 35.2561 13.2237 35.1267 11.8806C34.9413 9.95206 32.05 9.60083 30.7835 8.16378C29.5481 6.76145 29.3963 4.01857 27.2452 3.98769C25.929 3.96839 24.8789 4.3402 23.4693 3.92722C22.0598 3.51424 20.5718 1.63333 19.2232 1.83789L19.2182 1.83403ZM5.17212 42.2235H8.52004C8.5922 42.2235 9.17071 42.4139 9.27024 42.4743L11.868 45.4295L15.1512 38.3098C13.968 37.6717 12.5696 38.2416 11.2434 38.1233C9.67458 37.9818 8.62081 37.0387 8.08335 35.5528L5.03776 41.9636L5.17088 42.2247L5.17212 42.2235ZM30.4725 42.2235C31.5014 42.0897 32.7641 42.3225 33.8204 42.2235L33.9535 41.9623L30.9079 35.5515C30.3866 37.0156 29.2856 37.9843 27.7479 38.122C26.4216 38.2416 25.0232 37.6704 23.8401 38.3085L27.1233 45.4282L29.721 42.4731C29.8492 42.3959 30.3306 42.2415 30.4712 42.2235H30.4725ZM31.7166 20.1813C31.7166 27.1633 26.245 32.824 19.4969 32.824C12.7488 32.824 7.27717 27.1633 7.27717 20.1813C7.27717 13.1993 12.7488 7.53852 19.4969 7.53852C26.245 7.53852 31.7166 13.1993 31.7166 20.1813ZM29.9798 20.1761C29.9798 14.186 25.287 9.33066 19.4969 9.33066C13.7068 9.33066 9.01395 14.186 9.01395 20.1761C9.01395 26.1662 13.7068 31.0216 19.4969 31.0216C25.287 31.0216 29.9798 26.1662 29.9798 20.1761ZM13.1656 19.969C14.7394 21.2684 16.1987 23.4967 17.7576 24.7112C18.305 25.1383 18.4481 25.1434 19.003 24.7112C20.1724 23.8016 24.5107 19.3129 25.3903 18.1035C26.0745 17.1631 25.2945 16.2702 24.3863 16.6793L18.4431 22.7235C18.0711 22.7235 15.2009 19.2884 14.5291 18.815C14.1198 18.5268 13.5985 18.3454 13.2054 18.7751C13.0013 18.9977 12.9678 19.7078 13.1668 19.969H13.1656Z\" fill=\"#623D6A\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0623\u0642\u0645\u0634\u0629 \u0641\u0627\u062e\u0631\u0629<br> \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>VELOURA COLLECTION \u00a0\u062d\u064a\u062b \u064a\u0644\u062a\u0642\u064a \u0627\u0644\u062a\u0631\u0627\u062b \u0628\u0627\u0644\u0641\u062e\u0627\u0645\u0629 \u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646 \u0645\u0627 \u0627\u0644\u062c\u062f\u064a\u062f \u0644\u062f\u064a\u0646\u0627 AS-V-W-007 &#036;&nbsp;80 Select options This product has multiple variants. The options may be chosen on the product page \u0627\u0644\u0628\u0648\u062f\u064a\u0647\u0627\u062a &#036;&nbsp;17 Select options This product has multiple variants. The options may be chosen on the product page AS-V-W-006 &#036;&nbsp;80 Select options This product has multiple [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2007","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/pages\/2007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/comments?post=2007"}],"version-history":[{"count":161,"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/pages\/2007\/revisions"}],"predecessor-version":[{"id":7824,"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/pages\/2007\/revisions\/7824"}],"wp:attachment":[{"href":"https:\/\/aands2.followme.qa\/ar\/wp-json\/wp\/v2\/media?parent=2007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}